{"id":1446,"count":1,"description":"","link":"https:\/\/cnelindia.com\/blog\/tag\/user-engagement-analysis\/","name":"user engagement analysis","slug":"user-engagement-analysis","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>user engagement analysis Archives - CnEL India<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnelindia.com\/blog\/tag\/user-engagement-analysis\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"user engagement analysis Archives - CnEL India\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnelindia.com\/blog\/tag\/user-engagement-analysis\/\" \/>\n<meta property=\"og:site_name\" content=\"CnEL India\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/cnelindia.com\/blog\/tag\/user-engagement-analysis\/\",\"url\":\"https:\/\/cnelindia.com\/blog\/tag\/user-engagement-analysis\/\",\"name\":\"user engagement analysis Archives - CnEL India\",\"isPartOf\":{\"@id\":\"https:\/\/cnelindia.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/cnelindia.com\/blog\/tag\/user-engagement-analysis\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cnelindia.com\/blog\/tag\/user-engagement-analysis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cnelindia.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"user engagement analysis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cnelindia.com\/blog\/#website\",\"url\":\"https:\/\/cnelindia.com\/blog\/\",\"name\":\"CnEL India\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/cnelindia.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cnelindia.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cnelindia.com\/blog\/#organization\",\"name\":\"CnEL India\",\"url\":\"https:\/\/cnelindia.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cnelindia.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cnelindia.com\/blog\/wp-content\/uploads\/2024\/09\/logo-2.png\",\"contentUrl\":\"https:\/\/cnelindia.com\/blog\/wp-content\/uploads\/2024\/09\/logo-2.png\",\"width\":59,\"height\":59,\"caption\":\"CnEL India\"},\"image\":{\"@id\":\"https:\/\/cnelindia.com\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"user engagement analysis Archives - CnEL India","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnelindia.com\/blog\/tag\/user-engagement-analysis\/","og_locale":"en_US","og_type":"article","og_title":"user engagement analysis Archives - CnEL India","og_url":"https:\/\/cnelindia.com\/blog\/tag\/user-engagement-analysis\/","og_site_name":"CnEL India","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cnelindia.com\/blog\/tag\/user-engagement-analysis\/","url":"https:\/\/cnelindia.com\/blog\/tag\/user-engagement-analysis\/","name":"user engagement analysis Archives - CnEL India","isPartOf":{"@id":"https:\/\/cnelindia.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/cnelindia.com\/blog\/tag\/user-engagement-analysis\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/cnelindia.com\/blog\/tag\/user-engagement-analysis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cnelindia.com\/blog\/"},{"@type":"ListItem","position":2,"name":"user engagement analysis"}]},{"@type":"WebSite","@id":"https:\/\/cnelindia.com\/blog\/#website","url":"https:\/\/cnelindia.com\/blog\/","name":"CnEL India","description":"","publisher":{"@id":"https:\/\/cnelindia.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnelindia.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/cnelindia.com\/blog\/#organization","name":"CnEL India","url":"https:\/\/cnelindia.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cnelindia.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/cnelindia.com\/blog\/wp-content\/uploads\/2024\/09\/logo-2.png","contentUrl":"https:\/\/cnelindia.com\/blog\/wp-content\/uploads\/2024\/09\/logo-2.png","width":59,"height":59,"caption":"CnEL India"},"image":{"@id":"https:\/\/cnelindia.com\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cnelindia.com\/blog\/wp-json\/wp\/v2\/tags\/1446"}],"collection":[{"href":"https:\/\/cnelindia.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/cnelindia.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/cnelindia.com\/blog\/wp-json\/wp\/v2\/posts?tags=1446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}